{"id":244,"date":"2014-08-16T18:50:29","date_gmt":"2014-08-16T16:50:29","guid":{"rendered":"http:\/\/sunnysjourney.de\/wp-content\/uploads\/2014\/08\/10615830_758436870885928_1960099899_n.jpg"},"modified":"2016-01-22T19:41:17","modified_gmt":"2016-01-22T17:41:17","slug":"10615830_758436870885928_1960099899_n","status":"inherit","type":"attachment","link":"https:\/\/sunnysjourney.de\/en\/hang-zum-mittelalter\/10615830_758436870885928_1960099899_n\/","title":{"rendered":"10615830_758436870885928_1960099899_n"},"author":2,"comment_status":"open","ping_status":"open","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/sunnysjourney.de\/wp-content\/uploads\/2014\/08\/10615830_758436870885928_1960099899_n.jpg'><img loading=\"lazy\" width=\"200\" height=\"300\" src=\"https:\/\/sunnysjourney.de\/wp-content\/uploads\/2014\/08\/10615830_758436870885928_1960099899_n-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/sunnysjourney.de\/wp-content\/uploads\/2014\/08\/10615830_758436870885928_1960099899_n-200x300.jpg 200w, https:\/\/sunnysjourney.de\/wp-content\/uploads\/2014\/08\/10615830_758436870885928_1960099899_n.jpg 640w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Hang zum Mittelalter<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":640,"height":960,"file":"2014\/08\/10615830_758436870885928_1960099899_n.jpg","sizes":{"thumbnail":{"file":"10615830_758436870885928_1960099899_n-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/sunnysjourney.de\/wp-content\/uploads\/2014\/08\/10615830_758436870885928_1960099899_n-150x150.jpg"},"medium":{"file":"10615830_758436870885928_1960099899_n-200x300.jpg","width":200,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/sunnysjourney.de\/wp-content\/uploads\/2014\/08\/10615830_758436870885928_1960099899_n-200x300.jpg"},"post-thumbnail":{"file":"10615830_758436870885928_1960099899_n-604x270.jpg","width":604,"height":270,"mime_type":"image\/jpeg","source_url":"https:\/\/sunnysjourney.de\/wp-content\/uploads\/2014\/08\/10615830_758436870885928_1960099899_n-604x270.jpg"},"full":{"file":"10615830_758436870885928_1960099899_n.jpg","width":640,"height":960,"mime_type":"image\/jpeg","source_url":"https:\/\/sunnysjourney.de\/wp-content\/uploads\/2014\/08\/10615830_758436870885928_1960099899_n.jpg"}},"image_meta":{"aperture":0,"credit":"Ramona Keller","camera":"","caption":"","created_timestamp":0,"copyright":"(c) Negativ","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":242,"source_url":"https:\/\/sunnysjourney.de\/wp-content\/uploads\/2014\/08\/10615830_758436870885928_1960099899_n.jpg","_links":{"self":[{"href":"https:\/\/sunnysjourney.de\/en\/wp-json\/wp\/v2\/media\/244"}],"collection":[{"href":"https:\/\/sunnysjourney.de\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/sunnysjourney.de\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/sunnysjourney.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sunnysjourney.de\/en\/wp-json\/wp\/v2\/comments?post=244"}]}}